{"id":4691,"date":"2012-08-14T01:20:20","date_gmt":"2012-08-14T00:20:20","guid":{"rendered":"http:\/\/www.lespassengers.com\/?p=4691"},"modified":"2021-02-23T10:54:33","modified_gmt":"2021-02-23T10:54:33","slug":"les-chapeaux-panamas-sont-equatoriens","status":"publish","type":"post","link":"https:\/\/www.lespassengers.com\/index.php\/2012\/08\/14\/les-chapeaux-panamas-sont-equatoriens\/","title":{"rendered":"Les chapeaux Panamas sont \u00e9quatoriens&#8230;"},"content":{"rendered":"<figure id=\"attachment_4870\" aria-describedby=\"caption-attachment-4870\" style=\"width: 415px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-4870 \" title=\"panama\" src=\"https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/08\/panama.jpeg\" alt=\"\" width=\"415\" height=\"576\" srcset=\"https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/08\/panama.jpeg 519w, https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/08\/panama-216x300.jpeg 216w\" sizes=\"auto, (max-width: 415px) 100vw, 415px\" \/><figcaption id=\"caption-attachment-4870\" class=\"wp-caption-text\">cr\u00e9dit photo: Mai Suzuki @maiuniverse<\/figcaption><\/figure>\n<p>Arriv\u00e9 en Equateur, mon oeil a \u00e9t\u00e9 attir\u00e9 par de jolis chapeaux en fibre, qui m&#8217;ont rappel\u00e9 la forme du c\u00e9l\u00e8bre couvre chef d&#8217;Al Capone. Les Cholita locales (pour ceux qui auraient oubli\u00e9 ce que sont les cholitas, <a title=\"Les Cholitas\u2026\" href=\"https:\/\/www.lespassengers.com\/?p=4127\" target=\"_blank\" rel=\"noopener\">petit cours de rattrapage ici<\/a>) n&#8217;arboraient pas les traditionnels chapeaux melons port\u00e9s par les Boliviennes, mais ces sombreros d&#8217;un autre genre.<br \/>\nRenseignements pris, je d\u00e9couvre que ces fameux chapeaux portent le nom de Panama, ils sont pourtant bel et bien originaires d&#8217;Equateur. Je d\u00e9cide de mener l&#8217;enqu\u00eate et me rends dans le petit village de Sig Sig, dans le centre du pays, o\u00f9 une coop\u00e9rative g\u00e9r\u00e9e par les femmes du village fabrique et vend ces fameux Panama.<br \/>\nLes premi\u00e8res traces des chapeaux panama remontent \u00e0 4000 av JC. Des d\u00e9couvertes arch\u00e9ologiques mettent \u00e0 jour la pr\u00e9sence de chapeaux utilisant des techniques de tissage similaires \u00e0 celles toujours utilis\u00e9es aujourd&#8217;hui. Il faut n\u00e9anmoins attendre l&#8217;arriv\u00e9e des Espagnols au XVI\u00e8me si\u00e8cle, pour que les europ\u00e9ens s&#8217;int\u00e9ressent \u00e0 ces chapeaux finement tiss\u00e9s. Ils sont ramen\u00e9s sur le vieux continent pour la premi\u00e8re fois au cours de l&#8217;exposition universelle de Paris en 1855, et impressionnent par la finesse de leur fibre et la technicit\u00e9 de leur tissage.<br \/>\nAu d\u00e9but du XX\u00e8me si\u00e8cle d\u00e9bute la construction du canal de Panama. Des ouvriers du monde entier affluent pour travailler sur ce gigantesque chantier. Pour se prot\u00e9ger du soleil de plomb panam\u00e9en, ils ach\u00e8tent en masse des chapeaux de paille \u00e9quatorien. Malgr\u00e9 son origine, son utilisation massive au Panama lui donne son nom de bapt\u00eame: l&#8217;appellation Panama est n\u00e9e. Ce nom ressort renforc\u00e9 des premi\u00e8res exportations faites depuis l&#8217;Equateur \u00e0 destination de l&#8217;Europe et des Etats-Unis, et qui transitent depuis toutes par le Panama. Le malentendu s&#8217;installe et le &#8220;Sombrero de Paja Toquilla&#8221; est d\u00e9finitivement renomm\u00e9 chapeau Panama.<\/p>\n<figure id=\"attachment_4877\" aria-describedby=\"caption-attachment-4877\" style=\"width: 327px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-4877  \" title=\"IMG_8121_test\" src=\"https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/08\/IMG_8121_test1-682x1024.jpg\" alt=\"\" width=\"327\" height=\"491\" \/><figcaption id=\"caption-attachment-4877\" class=\"wp-caption-text\">coop\u00e9rative de Sig Sig: tissage manuel de chapeau Panama<\/figcaption><\/figure>\n<p>Les chapeaux Panama sont largement disponibles dans tout l&#8217;Equateur, mais la visite du village de Sig Sig pr\u00e9sente l&#8217;opportunit\u00e9 de d\u00e9couvrir tout le processus de fabrication, et d&#8217;observer \u00e0 quel point l&#8217;\u00e9conomie de ce pueblo tourne quasi uniquement autour de ce chapeau. Sa fabrication peut prendre de plusieurs jours, \u00e0 plusieurs semaines, voire plusieurs mois en fonction de la finesse du tissage.<br \/>\nEn d\u00e9ambulant dans les rues de la ville, je constate que toutes les femmes que je croise sont occup\u00e9es au tissage de chapeaux, quasi machinalement, tout en continuant \u00e0 vaquer \u00e0 d&#8217;autres occupations. L&#8217;une allaite son b\u00e9b\u00e9 tout en tissant, l&#8217;autre vend des fruits sur le march\u00e9, je croise m\u00eame une jeune femme marchant en pleine rue tout \u00a0en tissant des fibres qu&#8217;elle avait pris le soin au pr\u00e9alable de fixer \u00e0 sa robe.<\/p>\n<figure id=\"attachment_4871\" aria-describedby=\"caption-attachment-4871\" style=\"width: 491px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-4871  \" title=\"IMG_8132_test\" src=\"https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/08\/IMG_8132_test-1024x682.jpg\" alt=\"\" width=\"491\" height=\"327\" srcset=\"https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/08\/IMG_8132_test-1024x682.jpg 1024w, https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/08\/IMG_8132_test-300x200.jpg 300w, https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/08\/IMG_8132_test-768x512.jpg 768w, https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/08\/IMG_8132_test.jpg 1280w\" sizes=\"auto, (max-width: 491px) 100vw, 491px\" \/><figcaption id=\"caption-attachment-4871\" class=\"wp-caption-text\">une vieille dame tissant un chapeau Panama dans sa boutique<\/figcaption><\/figure>\n<p>Au d\u00e9tour d&#8217;une rue, j&#8217;aper\u00e7ois une vieille dame dans sa boutique. Elle a derri\u00e8re ses grosses lunettes, un visage fort sympathique, et je ne r\u00e9siste pas au plaisir d&#8217;entamer la conversation avec elle. Tandis que nous parlons, j&#8217;observe ses mains rid\u00e9es danser d&#8217;une fibre \u00e0 l&#8217;autre, tressant la structure de ce qui sera bient\u00f4t un de ces c\u00e9l\u00e8bres chapeaux. J&#8217;ai tr\u00e8s envie de la prendre en photo, mais j&#8217;h\u00e9site \u00e0 lui demander, conscient que beaucoup d&#8217;indig\u00e8nes, tr\u00e8s superstitieux, n&#8217;appr\u00e9cient pas cet exercice. Apr\u00e8s avoir h\u00e9sit\u00e9 de longues minutes, je me lance finalement. Sa r\u00e9ponse est tellement po\u00e9tique que je vou sla livre dans son int\u00e9gralit\u00e9.<\/p>\n<blockquote><p><em>&#8211; Excusez-moi Madame, j&#8217;aime beaucoup votre expression et j&#8217;aimerai savoir si je peux prendre une photo de vous?<\/em><br \/>\n<em>&#8211; Est-ce que tu m&#8217;emmenas avec toi si tu me prends en photo?<\/em><br \/>\n<em>&#8211; ?????<\/em><br \/>\n<em>&#8211; Tu vas retourner en France apr\u00e8s ton voyage?<\/em><br \/>\n<em>&#8211; Euh&#8230; oui&#8230;<\/em><br \/>\n<em>&#8211; Et bien si tu me promets d&#8217;emmener ma photo avec toi en France, c&#8217;est d&#8217;accord: j&#8217;ai toujours r\u00eav\u00e9 de visiter l&#8217;Europe<\/em><\/p><\/blockquote>\n<p>Et un p\u00eale m\u00eale pour illustrer Sig Sig<\/p>\n<p><center><object width=\"400\" height=\"300\"><param name=\"flashvars\" value=\"offsite=true&amp;lang=en-us&amp;page_show_url=%2Fphotos%2Flespassengers%2Fsets%2F72157631024273852%2Fshow%2F&amp;page_show_back_url=%2Fphotos%2Flespassengers%2Fsets%2F72157631024273852%2F&amp;set_id=72157631024273852&amp;jump_to=\" \/><param name=\"movie\" value=\"http:\/\/www.flickr.com\/apps\/slideshow\/show.swf?v=109615\" \/><param name=\"allowFullScreen\" value=\"true\" \/><\/object><\/center><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arriv\u00e9 en Equateur, mon oeil a \u00e9t\u00e9 attir\u00e9 par de jolis chapeaux en fibre, qui m&#8217;ont rappel\u00e9 la forme du &hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[6,33,60,154,184],"tags":[],"class_list":["post-4691","post","type-post","status-publish","format-standard","hentry","category-anecdote","category-chapeaux","category-equateur","category-pelle-mele","category-sig-sig"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts\/4691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/comments?post=4691"}],"version-history":[{"count":1,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts\/4691\/revisions"}],"predecessor-version":[{"id":7112,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts\/4691\/revisions\/7112"}],"wp:attachment":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/media?parent=4691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/categories?post=4691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/tags?post=4691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}