{"id":4292,"date":"2012-07-01T01:00:11","date_gmt":"2012-07-01T00:00:11","guid":{"rendered":"http:\/\/www.lespassengers.com\/?p=4292"},"modified":"2021-06-03T14:29:53","modified_gmt":"2021-06-03T14:29:53","slug":"v6-et-v8-soyez-benis","status":"publish","type":"post","link":"https:\/\/www.lespassengers.com\/index.php\/2012\/07\/01\/v6-et-v8-soyez-benis\/","title":{"rendered":"V6 et V8, soyez b\u00e9nis!"},"content":{"rendered":"<p>\u00a0<\/p>\n<figure id=\"attachment_4325\" aria-describedby=\"caption-attachment-4325\" style=\"width: 355px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"   wp-image-4325 \" title=\"IMG_3879_test\" src=\"https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/06\/IMG_3879_test-682x1024.jpg\" alt=\"\" width=\"355\" height=\"644\" \/><figcaption id=\"caption-attachment-4325\" class=\"wp-caption-text\">s\u00e9ance de b\u00e9n\u00e9diction d&#8217;un Toyota Hillux \u00e0 Copacabana<\/figcaption><\/figure>\n<p>Je vous avais expliqu\u00e9 dans mon dernier article que la ville de Copacabana, hormis son nom qui fait r\u00e9f\u00e9rence \u00e0 la fameuse plage br\u00e9silienne et qui en fait r\u00eaver plus d&#8217;un, ne pr\u00e9sente que gu\u00e8re d&#8217;int\u00e9r\u00eat. Je me suis peut-\u00eatre un peu trop avanc\u00e9 en disant cela, car une c\u00e9r\u00e9monie qui se d\u00e9roule tous les week-end vaut largement le d\u00e9tour.<\/p>\n<p>La ville abrite la cath\u00e9drale de Copacabana qui t\u00e9moigne des influences arabes des Espagnols: domes, mosaiques sur de nombreuses facades. L&#8217;importance du lieu provient du fait qu&#8217;elle abrite la vierge de Copacabana, une statue\u00a0en bois du XVI\u00e8me aux traits indig\u00e8nes, sculpt\u00e9e par un Indien. La vierge de Copacabana est la patronne de la Bolivie et est \u00e9galement v\u00e9n\u00e9r\u00e9e au P\u00e9rou.<\/p>\n<p>Mais au del\u00e0 de sa belle architecture, ce qui a retenu mon attention aux abords de la cath\u00e9drale se sont les \u00e9tranges c\u00e9r\u00e9monies de b\u00e9n\u00e9dictions qui se d\u00e9roulent chaque week-end. Tous les samedis et dimanches aux alentours de dix heures, une longue file de v\u00e9hicules se forment devant le parvis de l&#8217;\u00e9glise. Voitures, vans, bus, capot ouvert et colliers de fleurs d\u00e9coratifs suspendus au capot, r\u00e9troviseurs et antennes, forment une longue ligne le long de la rue principale de la ville. Plusieurs jeunes pr\u00eatres se relaient seau d&#8217;eau b\u00e9nite \u00e0 la main pour proc\u00e9der \u00e0 la b\u00e9n\u00e9diction de ces v\u00e9hicules nouvellement acquis par leurs propri\u00e9taires.<\/p>\n<figure id=\"attachment_4328\" aria-describedby=\"caption-attachment-4328\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"   wp-image-4328 size-large\" title=\"IMG_3886_test\" src=\"https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/06\/IMG_3886_test-1-1024x682.jpg\" alt=\"\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/06\/IMG_3886_test-1-1024x682.jpg 1024w, https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/06\/IMG_3886_test-1-300x200.jpg 300w, https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/06\/IMG_3886_test-1-768x512.jpg 768w, https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/06\/IMG_3886_test-1.jpg 1280w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-4328\" class=\"wp-caption-text\">les v\u00e9hicules sont d\u00e9cor\u00e9s de couronnes de fleurs pour l&#8217;occasion, comme cette Wolkswagen hors d&#8217;age<\/figcaption><\/figure>\n<p>Apr\u00e8s avoir asperg\u00e9 les v\u00e9hicules, les propri\u00e9taires et le pr\u00eatre se mettent en cercle en se tenant la main et r\u00e9citent des pri\u00e8res durant encore quelques minutes, pour s&#8217;assurer que le d\u00e9mon restera \u00e9loign\u00e9. La s\u00e9ance de pri\u00e8res termin\u00e9e, le v\u00e9hicule est alors asperg\u00e9 de mousseux et l&#8217;on jette des p\u00e9tards pour c\u00e9l\u00e9brer le bapt\u00eame du v\u00e9hicule. Les plus observateurs peuvent aussi observer \u00e0 la fin de la c\u00e9r\u00e9monie une\u00a0enveloppe passer discr\u00e8tement des mains du\u00a0propri\u00e9taire\u00a0\u00e0 celles du pr\u00eatre, mais je suis convaincu que cela n&#8217;est que pour s&#8217;assurer de la qualit\u00e9 de la protection divine.<\/p>\n<p>J&#8217;ai entendu dire que c&#8217;est lors de la semaine sainte que la foule de v\u00e9hicules est le plus nombreuses. Des compagnies boliviennes\u00a0de car\u00a0am\u00e8neraient d&#8217;ailleurs \u00e0 cette p\u00e9riode leur flotte au grand complet pour qu&#8217;elle re\u00e7oive quelques gouttes d&#8217;eau b\u00e9nite pour garder le malin \u00e9loign\u00e9. A ceux que cela pourrait laisser perplexe, des Boliviens qui faisaient la queue pour obtenir cette b\u00e9n\u00e9diction protectrice m&#8217;ont expliqu\u00e9 que malgr\u00e9 la contribution demand\u00e9e par l&#8217;\u00e9glise, cela revenait nettement moins cher de venir \u00e0 Copacabana que de faire assurer son v\u00e9hicule: vu comme \u00e7a, c&#8217;est implacable!<\/p>\n<p>Et un petit coup de vid\u00e9o pour que vous aussi vous preniez quelques \u00e9claboussure d&#8217;eau b\u00e9nite<\/p>\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jetpack-video-wrapper\"><iframe loading=\"lazy\" title=\"Copacabana - Car Blessing\" src=\"https:\/\/player.vimeo.com\/video\/44588751?dnt=1&amp;app_id=122963\" width=\"640\" height=\"360\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Et all\u00e9luia, un p\u00eale m\u00eame:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-flickr wp-block-embed-flickr\"><div class=\"wp-block-embed__wrapper\">\n<a data-flickr-embed='true' href='https:\/\/www.flickr.com\/photos\/lespassengers\/albums\/72157630253679184' title='Copacabana Car Blessing by lespassengers, on Flickr'><img src='https:\/\/live.staticflickr.com\/8152\/7333097174_77b956ef04_c.jpg' width='800' height='600' alt='IMG_3857_test'><\/a><script async src='https:\/\/embedr.flickr.com\/assets\/client-code.js' charset='utf-8'><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Je vous avais expliqu\u00e9 dans mon dernier article que la ville de Copacabana, hormis son nom qui fait r\u00e9f\u00e9rence &hellip; <\/p>\n","protected":false},"author":1,"featured_media":4326,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,39,49,55,83,84,125,154,202,225],"tags":[],"class_list":["post-4292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bolivie","category-copacabana","category-decale","category-eglises","category-humour","category-ile","category-misc","category-pelle-mele","category-titicaca","category-video"],"jetpack_featured_media_url":"https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/06\/IMG_3879_test-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts\/4292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/comments?post=4292"}],"version-history":[{"count":2,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts\/4292\/revisions"}],"predecessor-version":[{"id":7801,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts\/4292\/revisions\/7801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/media\/4326"}],"wp:attachment":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/media?parent=4292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/categories?post=4292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/tags?post=4292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}