{"id":3977,"date":"2012-04-05T03:06:57","date_gmt":"2012-04-05T02:06:57","guid":{"rendered":"http:\/\/www.lespassengers.com\/?p=3977"},"modified":"2021-06-03T11:04:36","modified_gmt":"2021-06-03T11:04:36","slug":"depart-mouvemente-de-terre-de-feu","status":"publish","type":"post","link":"https:\/\/www.lespassengers.com\/index.php\/2012\/04\/05\/depart-mouvemente-de-terre-de-feu\/","title":{"rendered":"D\u00e9part (mouvement\u00e9) de Terre de Feu"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En quittant Ushuaia, et en regardant le canal de Beagle s\u2019\u00e9loigner dans mon r\u00e9troviseur, je prends conscience que la route vers Buenos Aires va \u00eatre longue. 5200 kilom\u00e8tres pour \u00eatre pr\u00e9cis, qui vont consister principalement en une grande ligne droite qui traverse le gigantesque d\u00e9sert patagonien.<br>J\u2019ai arr\u00eat\u00e9 deux \u00e9tapes: la premi\u00e8re est Punta Arenas au Chili, une \u00e9tape logistique pour faire d\u00e9cabosser le cul de la Ch\u00e9rie Moya (<a href=\"https:\/\/www.lespassengers.com\/?p=3649\">cf article pr\u00e9c\u00e9dent<\/a>). La seconde \u00e0 la P\u00e9ninsule de Vald\u00e8s pour essayer d\u2019observer les orques tueurs\u00a0 qui attaquent les b\u00e9b\u00e9s phoques sur les plages \u00e0 la fin de l\u2019\u00e9t\u00e9. La vid\u00e9o ci-dessous n&#8217;est pas de moi, mais donne une id\u00e9e du spectacle<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jetpack-video-wrapper\"><iframe loading=\"lazy\" title=\"Orcas of Peninsula Valdes (HD)\" width=\"750\" height=\"422\" src=\"https:\/\/www.youtube.com\/embed\/4s2_qGeLEhQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n<p>Premi\u00e8re \u00e9tape, quitter la Terre de Feu. En suivant les conseils du motard argentin qui m\u2019h\u00e9berge \u00e0 Ushuaia, je choisis de franchir la fronti\u00e8re argentino-chilienne \u00e0 Bella Vista. Le chemin qui y m\u00e8ne traverse de jolis paysages, mais surtout, les camions n\u2019empruntent pas cette route qui est d\u00e9serte.<br \/>J\u2019arrive du cot\u00e9 argentin vers 19 heures. Il y a quatre maisons peintes en vert fonc\u00e9, couleur de la gendarmerie argentine. Alors que je descends de mon v\u00e9hicule, j\u2019aper\u00e7ois au loin une femme en peignoir rentrer chez elle. Je commence \u00e0 \u00e9tablir les premi\u00e8res formalit\u00e9s avec un jeune gendarme, qui para\u00eet tout \u00e9tonn\u00e9 de voir un touriste ici. Pas d\u2019ordinateur, juste de la paperasse et un cahier aux pages jaunies, o\u00f9 le dernier passage recens\u00e9 date de 5 jours. Les papiers d\u2019immigration remplis, la femme que j\u2019ai aper\u00e7ue quelques minutes plus t\u00f4t entre dans le bureau. Plus de peignoir cette fois-ci mais un treillis avec un pistolet \u00e0 la ceinture et un blouson adouana (douane)<\/p>\n<figure id=\"attachment_4010\" aria-describedby=\"caption-attachment-4010\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"   wp-image-4010 size-large\" title=\"bella_vista_border_anto\" src=\"https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/03\/bella_vista_border_anto-1024x640.jpg\" alt=\"\" width=\"750\" height=\"469\" srcset=\"https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/03\/bella_vista_border_anto-1024x640.jpg 1024w, https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/03\/bella_vista_border_anto-300x188.jpg 300w, https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/03\/bella_vista_border_anto-768x480.jpg 768w, https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/03\/bella_vista_border_anto.jpg 1280w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-4010\" class=\"wp-caption-text\">Poste fronti\u00e8re de Bella Vista<\/figcaption><\/figure>\n<p><br \/>Elle tient par la main son fils qui joue avec la sonnette sans fil de la porte du bureau de douane. Elle remplit les papiers d\u2019importation de mon v\u00e9hicule sous les &#8220;ding dong&#8221; du carillon que le gosse n\u2019arr\u00eate pas d\u2019activer.<br \/>Apr\u00e8s avoir termin\u00e9 les papiers, le douanier m\u2019ouvre la barri\u00e8re en bois qui barre la route. En voyant la Ch\u00e9rie Moya, il me regarde h\u00e9b\u00e9t\u00e9 en me demandant si je suis s\u00fbr de pouvoir passer au Chili. Je ne comprends pas trop au d\u00e9but, et puis apr\u00e8s quelques dizaines de m\u00e8tres, eur\u00eaka: un ruisseau! Mais regardez plut\u00f4t les images\u2026<br \/>\u00a0<\/p>\n<p style=\"text-align: center;\">[vimeo 39298343]<\/p>\n<p>\u00a0<br \/>La voiture traverse sans souci et je peux \u00e9tablir les formalit\u00e9s d\u2019entr\u00e9e au Chili, devant des douaniers aussi surpris que leurs coll\u00e8gues argentins de me voir arriver. Une diff\u00e9rence peut-\u00eatre, aucun des trois agents n\u2019est en peignoir de ce cot\u00e9 ci de la fronti\u00e8re.<br \/><br \/>Aimant le risque, j\u2019ai d\u00e9cid\u00e9 de faire entrer ill\u00e9galement un saucisson argentin au Chili (quarantaine oblige, l\u2019entr\u00e9e de bouffe au Chili est formellement interdite et s\u00e9v\u00e8rement r\u00e9primand\u00e9e : 1000 dollars d\u2019amende). Pour ne pas me faire confisquer ma pr\u00e9cieuse saucisse s\u00e8che, je l\u2019ai pli\u00e9e dans un sac plastique que j\u2019ai dissimul\u00e9 sous le capot de la voiture. Bonne id\u00e9e\u2026 sauf que je n\u2019avais pas pr\u00e9vu de traverser un ruisseau en voiture.<br \/>Heureusement, le Saint Protecteur des amoureux de charcuterie est l\u00e0, et de sa main protectrice a prot\u00e9g\u00e9 mon Justin Bridou de l&#8217;inondation. Pas une seule trace d&#8217;humidit\u00e9 et je peux m&#8217;en d\u00e9lecter pour le diner au milieu de la pampa o\u00f9 j&#8217;ai \u00e9tabli mon campement.<br \/><br \/>Le lendemain, je reprends la route en me disant que tout para\u00eet un peu trop facile; en y r\u00e9fl\u00e9chissant, je me dis que c&#8217;est presque triste de ne pas avoir une p\u00e9rip\u00e9tie \u00e0 raconter au sujet de mon s\u00e9jour sur l\u2019ile la plus australe du monde. Heureusement pour mon stock d\u2019histoires, une gal\u00e8re ne tarde pas \u00e0 arriver. Alors que je roule pour prendre le ferry, l\u2019aiguille de ma jauge \u00e0 essence commence \u00e0 dangereusement se rapprocher de 0.<br \/><br \/>La piste que j\u2019ai emprunt\u00e9e \u00e9vite la seule station service entre Ushuaia et l\u2019embarcad\u00e8re de ferry. Qu\u2019importe, ma carte routi\u00e8re indique qu\u2019il a une autre gazolina \u00e0 l\u2019embarcad\u00e8re. Dans un remake de l\u2019histoire que j\u2019avais v\u00e9cue au Vietnam (<a title=\"DMZ \u2013 Panne s\u00e8che en terres inconnues\u2026\" href=\"https:\/\/www.lespassengers.com\/?p=3212\">rappel ici pour ceux qui auraient oubli\u00e9<\/a>), je rigole en regardant l\u2019aiguille de mon r\u00e9servoir descendre. Alors que ca fait 70 kilom\u00e8tres que je tourne sur la r\u00e9serve, je me d\u00e9cide \u00e0 utiliser mon jerrican d\u2019urgence. Avec les 10 litres de plus, pas de souci, ca devrait le faire et je devrais bien arriver jusqu\u2019\u00e0 ce fameux embarcad\u00e8re\u2026 et j\u2019y arrive bien. Seul probl\u00e8me, la carte est erron\u00e9e et la station se trouve en fait \u00e0 100 kilom\u00e8tre au Sud d\u2019ici. Gloups\u2026 la lumi\u00e8re de ma r\u00e9serve est allum\u00e9e en orange depuis presque une heure.<br \/><br \/>Pas d&#8217;autre choix que d\u2019avancer, j\u2019embarque sur le ferry et m\u2019empresse de demander \u00e0 un matelot o\u00f9 je peux trouver du pr\u00e9cieux liquide. Il me pointe du doigt une petite cabane bleue du cot\u00e9 continentale du d\u00e9troit de Magellan, et me dit que de l\u2019essence y est vendue sous le manteau. Sauv\u00e9\u2026 sauf que les temps sont durs m\u00eame pour les revendeurs d\u2019essence, et que le monsieur n\u2019a plus que du diesel. C\u2019est ballot et ca ne me sert \u00e0 rien. Encore plus ballot, il me confirme que la station la plus proche est\u2026 \u00e0 Punta Arenas soit \u00e0 150 kilom\u00e8tres d\u2019ici. Impossible d\u2019arriver l\u00e0 bas avec les 20 km d\u2019autonomie qu\u2019il doit me rester.<\/p>\n<figure id=\"attachment_4016\" aria-describedby=\"caption-attachment-4016\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"     wp-image-4016 size-large\" title=\"IMG_0529_anto\" src=\"https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/03\/IMG_0529_anto-1024x682.jpg\" alt=\"\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/03\/IMG_0529_anto-1024x682.jpg 1024w, https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/03\/IMG_0529_anto-300x200.jpg 300w, https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/03\/IMG_0529_anto-768x512.jpg 768w, https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/03\/IMG_0529_anto.jpg 1280w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-4016\" class=\"wp-caption-text\">ferry me ramenant de Terre de Feu (visible \u00e0 &#8216;horizon) sur le continent<\/figcaption><\/figure>\n<p><br \/>Je d\u00e9cide d\u2019aller de voiture en voiture le long de la longue file de v\u00e9hicules qui attendent pour prendre le bateau, en mendiant du super aupr\u00e8s chacun d\u2019entre eux. \u00a0Sur une quinzaine de voitures\u2026 rien. Un chauffeur routier, d\u00e9termin\u00e9 \u00e0 vouloir m\u2019aider m\u2019engueule m\u00eame en me faisant culpabiliser de ne pas avoir acheter un v\u00e9hicule diesel pour qu\u2019il puisse m\u2019aider.\u00a0 Mais euuuuu\u2026\u00a0? c\u2019est pas de ma faute quand m\u00eame s&#8217;il n\u2019y a pas d\u2019essence dans ce pays!<br \/>Une lueur d\u2019espoir appara\u00eet lorsqu\u2019un conducteur de 4&#215;4 me propose de siphonner 10 litres dans son r\u00e9servoir pour me permettre de faire les 150 bornes. Merveilleux\u2026\u00a0 sauf qu\u2019il n\u2019a pas de tuyau. Me voici reparti passant de voiture en voiture pour mendier cette fois-ci un tuyau : coup de bol, l\u2019une des voiture est celle d\u2019un plombier qui se trimballe avec un tuyau d\u2019arrosage dans son coffre. Tout ca se pr\u00e9sente bien\u2026 sauf que le 4&#215;4 est \u00e9quip\u00e9 d\u2019une trappe anti reflux, pour justement \u00e9viter justement que des petits malins ne se servent dans le r\u00e9servoir. Je suis maudit.<br \/>Apr\u00e8s une heure d\u2019effort je d\u00e9cide de reprendre la route et de pousser la voiture aussi loin que possible. 18 kilom\u00e8tres plus tard et pour la premi\u00e8re fois de ma vie, je tombe en panne s\u00e8che. En descendant de voiture, j\u2019explose de rire en r\u00e9alisant que je suis en panne d\u2019essence au milieu\u2026 d\u2019un champs d\u2019extraction p\u00e9troli\u00e8re. Je longe la route en essayant d\u2019arr\u00eater les rares v\u00e9hicules qui passent, je vois \u00e0 ma gauche le D\u00e9troit de Magellan et \u00e0 ma droite\u2026 un pipeline d\u2019hydrocarbures\u2026 les boules.<br \/>Les rafales de vent\u00a0 me forcent \u00e0 marcher en faisant un angle de 45 degr\u00e9s; apr\u00e8s quelques kilom\u00e8tres, j\u2019aper\u00e7ois un b\u00e2timent en face duquel sont gar\u00e9s une cinquantaine de 4&#215;4. En entrant je comprend que c\u2019est un des centres op\u00e9rationnels de la compagnie p\u00e9troli\u00e8re qui exploite les forages du coin. Si eux n\u2019ont pas d\u2019essence personne n\u2019en aura. Je trouve le contre maitre qui me dit que toute leur flotte roule au diesel pour des raisons \u00e9conomiques. Impossible donc de m\u2019aider\u00a0: mais quelle blague!<br \/>Me voici reparti le long de la route comme un malheureux, lorsqu\u2019un camion s\u2019arr\u00eate \u00e0 ma hauteur. Je lui demande s\u2019il peut m\u2019amener \u00e0 Punta Arenas, mais le chauffeur routier \u00e0 une meilleure id\u00e9e\u2026 regardez plut\u00f4t:\u00a0<\/p>\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jetpack-video-wrapper\"><iframe loading=\"lazy\" title=\"Panne d&#039;essence en terre de Feu - Tierra del Fuego, Chile\" src=\"https:\/\/player.vimeo.com\/video\/39802414?dnt=1&amp;app_id=122963\" width=\"640\" height=\"360\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s m\u2019avoir tract\u00e9 sur une trentaine de kilom\u00e8tres il m\u2019arr\u00eate \u00e0 cot\u00e9 d\u2019une raffinerie. Je n\u2019y crois pas une seule seconde, mais il me promet qu\u2019ils me vendront de l\u2019essence pour peu que j&#8217;ai de la monnaie chilienne. J\u2019ai l\u2019\u00e9quivalent de 14 euros. Aussi incroyable que cela puisse para\u00eetre, un employ\u00e9 de la raffinerie me vend 12 litres de super (l\u2019essence n\u2019est pas \u00e0 2 euros le litre au Chili\u00a0:-)), juste de quoi relier Punta Arenas\u2026 ouf!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En quittant Ushuaia, et en regardant le canal de Beagle s\u2019\u00e9loigner dans mon r\u00e9troviseur, je prends conscience que la route &hellip; <\/p>\n","protected":false},"author":1,"featured_media":4010,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[11,119,199,218,225],"tags":[],"class_list":["post-3977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-argentine","category-mecanique","category-terre-de-feu-argentine","category-ushuaia","category-video"],"jetpack_featured_media_url":"https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/03\/bella_vista_border_anto.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts\/3977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/comments?post=3977"}],"version-history":[{"count":3,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts\/3977\/revisions"}],"predecessor-version":[{"id":7751,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts\/3977\/revisions\/7751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/media\/4010"}],"wp:attachment":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/media?parent=3977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/categories?post=3977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/tags?post=3977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}