{"id":3845,"date":"2012-02-18T07:15:34","date_gmt":"2012-02-18T07:15:34","guid":{"rendered":"http:\/\/www.lespassengers.com\/?p=3845"},"modified":"2021-06-02T22:50:19","modified_gmt":"2021-06-02T22:50:19","slug":"antarctica-dont-worry-be-happy-feet","status":"publish","type":"post","link":"https:\/\/www.lespassengers.com\/index.php\/2012\/02\/18\/antarctica-dont-worry-be-happy-feet\/","title":{"rendered":"Antarctica: don&#8217;t worry, be happy&#8230; feet"},"content":{"rendered":"<p>\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3846 size-large\" title=\"IMG_9633_anto\" src=\"https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/02\/IMG_9633_anto-1024x520.jpg\" alt=\"\" width=\"750\" height=\"381\" srcset=\"https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/02\/IMG_9633_anto-1024x520.jpg 1024w, https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/02\/IMG_9633_anto-300x152.jpg 300w, https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/02\/IMG_9633_anto-768x390.jpg 768w, https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/02\/IMG_9633_anto.jpg 1280w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p style=\"text-align: left;\">Les premiers jours en Antarctique, on ne peut qu&#8217;\u00eatre \u00e9merveill\u00e9 par les adorables happy feets qui sont absolument partout. En escadrilles, il passent \u00e0 c\u00f4t\u00e9 du bateau en revenant de leur longue et lointaine partie de p\u00eache. Lorsque nous d\u00e9barquons sur la terre ferme, ils sont encore plus omnipr\u00e9sents, ils vivent en groupes au sein d&#8217;immenses colonies de plusieurs milliers de couples.<\/p>\n<p style=\"text-align: left;\">Comme si cela ne suffisait pas, ces curieux oiseaux avec des ailes mais qui ne volent pas, on les trouve aussi sur d&#8217;\u00e9norme icebergs \u00e0 la d\u00e9rive. Pas stress\u00e9s pour un sous.<\/p>\n<p style=\"text-align: left;\">L&#8217;Antarctique compte tellement de pingouins, qu&#8217;apr\u00e8s plusieurs jours pass\u00e9s sur place, on finit par ne plus s&#8217;\u00e9tonner d&#8217;en observer \u00e0 seulement quelques m\u00e8tres de nous. La meilleure preuve que l&#8217;on peut s&#8217;habituer \u00e0 tout. J&#8217;ai la chance d&#8217;\u00eatre sur place durant la p\u00e9riode des naissances. Dans toutes les colonies, les parents ont leurs petits serr\u00e9s contre eux et les sc\u00e8nes du quotidien pingouins sont toujours ultra attendrissante: entre la m\u00e8re qui nourrit son b\u00e9b\u00e9 par r\u00e9gurgitation o\u00f9 le p\u00e8re qui se bat avec un skua vicieux qui essaie \u00a0d&#8217;attaquer sa prog\u00e9niture, on ne peut pas vraiment se lasser d&#8217;observer ces amusantes cr\u00e9atures.<\/p>\n<p style=\"text-align: left;\">Cerise sur le gateau de l&#8217;\u00e9merveillement, la d\u00e9marche si particuli\u00e8re et si amusante de ces dr\u00f4les d&#8217;oiseaux. Si agiles sous l&#8217;eau, si maladroits et h\u00e9sitants sur terre. J&#8217;ai eu beau regarder des centaines de milliers de ces pingouins, supporter en silence leur odeur et leur manque d&#8217;hygi\u00e8ne criant (l&#8217;un m&#8217;a litt\u00e9ralement chi\u00e9 sur les bottes!), je ne me suis jamais lass\u00e9 de rire en les regardant. D&#8217;ailleurs il suffit de regarder le nombre de photos d&#8217;eux que j&#8217;ai pris pour comprendre qu&#8217;ils n&#8217;ont jamais cess\u00e9 de m&#8217;amuser.<\/p>\n<p style=\"text-align: left;\">Et en bonus, quelques vid\u00e9os pour les observer \u00e0 l&#8217;oeuvre<\/p>\n<p style=\"text-align: center;\">\u00a0<\/p>\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jetpack-video-wrapper\"><iframe loading=\"lazy\" title=\"At the same time, in Antarctica, two penguins...\" src=\"https:\/\/player.vimeo.com\/video\/37341700?dnt=1&amp;app_id=122963\" width=\"640\" height=\"360\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Les premiers jours en Antarctique, on ne peut qu&#8217;\u00eatre \u00e9merveill\u00e9 par les adorables happy feets qui sont absolument partout. &hellip; <\/p>\n","protected":false},"author":1,"featured_media":7184,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[349,10],"tags":[],"class_list":["post-3845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-antarctique"],"jetpack_featured_media_url":"https:\/\/www.lespassengers.com\/wp-content\/uploads\/2012\/02\/antartica-2-of-9-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts\/3845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/comments?post=3845"}],"version-history":[{"count":3,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts\/3845\/revisions"}],"predecessor-version":[{"id":7729,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts\/3845\/revisions\/7729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/media\/7184"}],"wp:attachment":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/media?parent=3845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/categories?post=3845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/tags?post=3845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}