{"id":2937,"date":"2011-09-16T12:00:15","date_gmt":"2011-09-16T11:00:15","guid":{"rendered":"http:\/\/www.lespassengers.com\/?p=2937"},"modified":"2021-06-07T23:22:13","modified_gmt":"2021-06-07T23:22:13","slug":"le-stress-du-passage-de-frontiere-vietnamienne","status":"publish","type":"post","link":"https:\/\/www.lespassengers.com\/index.php\/2011\/09\/16\/le-stress-du-passage-de-frontiere-vietnamienne\/","title":{"rendered":"Le stress du passage de fronti\u00e8re vietnamienne"},"content":{"rendered":"<p>Quelques jours avant de franchir la fronti\u00e8re vietnamienne, j&#8217;avais rencontr\u00e9 plusieurs overlanders (voyageurs qui se d\u00e9placent uniquement par la route avec leur propre v\u00e9hicule, ndlr), qui m&#8217;avaient un peu refroidi sur le Vietnam.<br \/>D&#8217;apr\u00e8s eux il \u00e9tait impossible d&#8217;entrer dans le pays avec un v\u00e9hicule immatricul\u00e9 \u00e0 l&#8217;\u00e9tranger.\u00a0La tuile: ne pas pouvoir finir ma travers\u00e9e d&#8217;Asie \u00e0 Hanoi comme pr\u00e9vu me chagrinait beaucoup. J&#8217;ai d\u00e9cid\u00e9 de m&#8217;accorder une journ\u00e9e pour effectuer mes propres investigations. Tout ce que j&#8217;ai pu trouver corroborait ces informations, mais en poussant mes recherches plus avant, j&#8217;ai fini par trouver 3 cas qui m&#8217;ont redonn\u00e9 un peu d&#8217;espoir et sembler remettre en cause l&#8217;issue fatale de l&#8217;entr\u00e9e au Vietnam.<\/p>\n<p>Les trois blogs \u00a0d\u00e9crivaient plus ou moins la m\u00eame m\u00e9thode. Tout d&#8217;abord se pr\u00e9senter \u00e0 la douane avec une lettre officielle de son ambassade, indiquant qu&#8217;elle se porte garant, et que son concitoyen ressortira bien du Vietnam avec son v\u00e9hicule et ne le revendra pas sur place (\u00e0 priori c&#8217;est \u00e0 cela que sert le carnet de passage en douane, mais les autorit\u00e9s Vietnamiennes n&#8217;ont pas du comprendre le principe du truc). Deuxi\u00e8mement, il faut pouvoir pr\u00e9senter une traduction certifi\u00e9e de son permis de conduire: et oui le Vietnam ne reconnait pas le permis de conduire international. Enfin il faut \u00eatre patient et g\u00e9n\u00e9reux, puisqu&#8217;apr\u00e8s s&#8217;\u00eatre pr\u00e9sent\u00e9 \u00e0 la douane, le processus prend en moyenne trois jours. On re\u00e7oit si tout va bien \u00e0 l&#8217;issue de ces trois jours une autorisation de rouler d\u00e9livr\u00e9e par le chef de la police du district d&#8217;o\u00f9 l&#8217;on a franchi la fronti\u00e8re. Elle autorise temporairement \u00e0 conduire au Vietnam. On re\u00e7oit aussi des plaques d&#8217;immatriculation temporaires\u00a0vietnamiennes. Bien sur tout cela coute plus ou moins cher en fonction du nombre d&#8217;interm\u00e9diaires \u00e0 qui il faut graisser la patte pour obtenir tous ces s\u00e9sames.<br \/><br \/>En discutant avec un allemand venu d&#8217;Europe en van, je d\u00e9couvre qu&#8217;un collegue motard avec lequel il a voyag\u00e9, et que je connais bien pour avoir pass\u00e9 plusieurs jour avec lui \u00e0 Mumbai (le monde est petit quand m\u00eame), a lui r\u00e9ussi \u00e0 entrer au Vietnam sans pr\u00e9esenter aucune de ces pi\u00e8ces, mais en passant par un minuscule poste de douane \u00e0 la fronti\u00e8re avec le Laos.<\/p>\n<p>La situation semble donc compliqu\u00e9e mais pas\u00a0d\u00e9sesp\u00e9r\u00e9e. Optimiste par nature, c&#8217;est le sentiment &#8220;si eux ont r\u00e9ussi pourquoi pas moi?&#8221; qui l&#8217;emporte. Pour corser un peu le tout, je me rends compte que j&#8217;ai perdu le V5 de ma moto (l&#8217;\u00e9quivalent de la carte grise). Je n&#8217;ai donc plus les papiers de mon v\u00e9hicule: bah&#8230; ca serait trop facile autrement.<\/p>\n<p>Une s\u00e9ance de photoshop plus tard, je me retrouve avec un faux V5 plus vrai que nature. Le fameuse lettre tamponn\u00e9e par les autorit\u00e9 fran\u00e7aise, je l&#8217;obtiendrai apr\u00e8s un coup de t\u00e9l\u00e9phone au consul de France du coin. par chance, c&#8217;est un homme absolument charmant qui a accept\u00e9 de me recevoir un samedi matin chez lui pour me tamponner le fameux papier avec de jolis tampons \u00a0&#8220;R\u00e9publique Fran\u00e7aise&#8221;\u00a0rouges et bleus du meilleur effet.<br \/>Arm\u00e9 de mon optimiste, de ma d\u00e9termination et de mon brin de folie, je choisis de tenter un passage \u00e0 Ha Tien. C&#8217;est un minuscule poste de douane, r\u00e9cemment ouvert aux touristes internationaux. La suite de l&#8217;histoire plut\u00f4t que de vous la raconter avec des mots, je vous la propose en images. Le montage a \u00e9t\u00e9 fait rapidement et sa qualit\u00e9 laisse un peu \u00e0 d\u00e9sirer, alors je vous demande d&#8217;\u00eatre indulgent.<\/p>\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jetpack-video-wrapper\"><iframe loading=\"lazy\" title=\"Vietnam border crossion\" src=\"https:\/\/player.vimeo.com\/video\/29071636?dnt=1&amp;app_id=122963\" width=\"640\" height=\"360\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">R\u00e9sultat des courses, Lizzy et moi m\u00eame nous promenons depuis maintenant une quinzaine de jours sur les routes vietnamiennes. Apr\u00e8s de plus amples recherches il semblerait que nous ne soyons qu&#8217;une petite dizaine \u00e0 avoir r\u00e9ussi \u00e0 entrer au Vietnam avec notre vehicule depuis les 5 derniers ann\u00e9es. N&#8217;ayant fait aucune d\u00e9marche administrative pour obtenir des plaques temporaires ou un permis de conduire provisoire, je suis \u00e9galement ici en toute in\u00e9galit\u00e9, mais \u00e7a, chut c&#8217;est un secret entre vous et moi.<br><br>So far so \u00a0good comme diraient les anglo saxons. J&#8217;ai pour l&#8217;instant \u00e9t\u00e9 arr\u00eat\u00e9 deux fois par la police. La premi\u00e8re fois, j&#8217;ai feint\u00e9 ne pas comprendre ce que signifiaient les grands mouvements de bras de l&#8217;agent et ne me suis pas arr\u00eat\u00e9. La seconde, j&#8217;ai jou\u00e9 l&#8217;idiot qui comprenait pas ce que l&#8217;on me disait; le policier a fini par perdre patience et m&#8217;a ordonn\u00e9 de partir. Il ne reste plus qu&#8217;\u00e0 esp\u00e9rer que cela marche jusqu&#8217;\u00e0 Hanoi!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quelques jours avant de franchir la fronti\u00e8re vietnamienne, j&#8217;avais rencontr\u00e9 plusieurs overlanders (voyageurs qui se d\u00e9placent uniquement par la route &hellip; <\/p>\n","protected":false},"author":1,"featured_media":7595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[6,28,225,226,232],"tags":[],"class_list":["post-2937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anecdote","category-cambodge","category-video","category-vietnam","category-visa"],"jetpack_featured_media_url":"https:\/\/www.lespassengers.com\/wp-content\/uploads\/2011\/09\/border-1-of-1-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts\/2937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/comments?post=2937"}],"version-history":[{"count":2,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts\/2937\/revisions"}],"predecessor-version":[{"id":8160,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts\/2937\/revisions\/8160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/media\/7595"}],"wp:attachment":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/media?parent=2937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/categories?post=2937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/tags?post=2937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}