{"id":63,"count":6,"description":"","link":"https:\/\/www.lespassengers.com\/index.php\/category\/finish-line\/","name":"finish line","slug":"finish-line","taxonomy":"category","parent":0,"meta":[],"z_taxonomy_image_url":"https:\/\/www.lespassengers.com\/wp-content\/plugins\/categories-images\/assets\/images\/placeholder.png","_links":{"self":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/categories\/63","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.lespassengers.com\/index.php\/wp-json\/wp\/v2\/posts?categories=63"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}